{"id":10002824,"date":"2025-09-18T14:22:39","date_gmt":"2025-09-18T12:22:39","guid":{"rendered":"https:\/\/praguecruises.eu\/event\/nachtfahrt-durch-prag-mit-buffet-september-und-oktober-2025\/"},"modified":"2025-09-18T14:39:54","modified_gmt":"2025-09-18T12:39:54","slug":"nachtfahrt-durch-prag-mit-buffet-september-und-oktober-2025","status":"publish","type":"tribe_events","link":"https:\/\/praguecruises.eu\/de\/event\/nachtfahrt-durch-prag-mit-buffet-september-und-oktober-2025\/2025-10-29\/","title":{"rendered":"Nachtfahrt durch Prag mit Buffet, September und Oktober 2025"},"content":{"rendered":"<div class=\"tribe-events-schedule tribe-clearfix\">\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\tOktober 29, 2025\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t, \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t20:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &ndash; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t22:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p><strong>Nachtfahrt durch Prag mit Buffet, September und Oktober 2025 &ndash; Erleben Sie einen einzigartigen Abend auf den Wellen der Moldau w&auml;hrend einer romantischen Nachtfahrt durch das historische Zentrum von Prag.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>W&auml;hrend der zweist&uuml;ndigen Schifffahrt genie&szlig;en Sie nicht nur atemberaubende Ausblicke auf die beleuchtete <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&lt;img width=&#039;200&#039; height=&#039;133&#039; src=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?fit=200%2C133&amp;amp;ssl=1&#039; class=&#039;cmtt-tooltip-featured-image wp-post-image&#039; alt=&#039;Prager burg&#039; style=&#039;width: 200px; margin-top: 2%;float: right; margin-left: 2%;&#039; sizes=&#039;(max-width: 9999px) 200px,auto&#039; loading=&#039;eager&#039; srcset=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?w=1200&amp;amp;ssl=1 1200w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=324%2C216&amp;amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=416%2C277&amp;amp;ssl=1 416w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=300%2C200&amp;amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=1024%2C683&amp;amp;ssl=1 1024w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=768%2C512&amp;amp;ssl=1 768w&#039; \/&gt;Die Prager Burg ist eine historische Festung und der Sitz der tschechischen Herrscher und Pr&auml;sidenten in Prag. Sie ist einer der gr&ouml;&szlig;ten Burgkomplexe der Welt und eine wichtige Touristenattraktion. &lt;\/div&gt;\"  href=\"https:\/\/praguecruises.eu\/de\/glossary\/prager-burg\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>Prager Burg<\/a>, die <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&lt;img width=&#039;200&#039; height=&#039;133&#039; src=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?fit=200%2C133&amp;amp;ssl=1&#039; class=&#039;cmtt-tooltip-featured-image wp-post-image&#039; alt=&#039;&#039; style=&#039;width: 200px; margin-top: 2%;float: right; margin-left: 2%;&#039; sizes=&#039;(max-width: 9999px) 200px,auto&#039; loading=&#039;eager&#039; srcset=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?w=1200&amp;amp;ssl=1 1200w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=324%2C216&amp;amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=416%2C277&amp;amp;ssl=1 416w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=300%2C200&amp;amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=1024%2C683&amp;amp;ssl=1 1024w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=768%2C512&amp;amp;ssl=1 768w&#039; \/&gt;Die Karlsbr&uuml;cke ist eine historische Steinbr&uuml;cke in Prag &uuml;ber die Moldau. Die Br&uuml;cke wurde im Auftrag von Kaiser Karl IV. erbaut und ist eines der ber&uuml;hmtesten Denkm&auml;ler der Tschechischen Republik.&lt;\/div&gt;\"  href=\"https:\/\/praguecruises.eu\/de\/glossary\/karlsbruecke\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>Karlsbr&uuml;cke<\/a> oder das Nationaltheater, sondern auch ein reichhaltiges Buffet mit tschechischen und internationalen Spezialit&auml;ten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/praguecruises.eu\/de\/schifffahrt\/prager-nachtkreuzfahrt-mit-buffet-abendessen-und-aperitif\/\" title=\"N&auml;chtliche Kreuzfahrt durch Prag mit Buffet-Abendessen und Aperitif\">N&auml;chtliche Moldaufahrt durch Prag mit Buffet-Abendessen und Aperitif<\/a><\/h2>\n\n\n<figure class=\"wp-block-post-featured-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"653\" src=\"https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?resize=980%2C653&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"No&#269;n&iacute; plavba Prahou s RAUTOVOU VE&#268;E&#344;&Iacute; a aperitivem &ndash; Osv&#283;tlen&yacute; no&#269;n&iacute; Karl&#367;v most\" style=\"object-fit:cover;\" srcset=\"https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?resize=768%2C511&amp;ssl=1 768w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?resize=324%2C216&amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/03\/nocni-plavba-prahou-s-rautovou-veceri-a-aperitivem-karluv-most.jpg?resize=416%2C277&amp;ssl=1 416w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\"\/><\/figure>\n\n\n<p>Wir laden Sie herzlich zu einer unvergesslichen zweist&uuml;ndigen Nachtfahrt auf der Moldau von 20:00 bis 22:00 Uhr ein. Genie&szlig;en Sie den Zauber der beleuchteten Prager Sehensw&uuml;rdigkeiten und lassen Sie sich mit einem Begr&uuml;&szlig;ungsgetr&auml;nk und einem reichhaltigen Abendessen vom Buffet verw&ouml;hnen. <\/p>\n\n\n\n<p><strong>Was Sie bei einer n&auml;chtlichen Schifffahrt durch Prag erwartet:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Begr&uuml;&szlig;ungsgetr&auml;nk:<\/strong> Ein Begr&uuml;&szlig;ungsgetr&auml;nk zur Einstimmung.<\/li>\n\n\n\n<li><strong>Reichhaltiges Abendessen:<\/strong> Das Abendessen wird in Buffetform serviert und umfasst eine gro&szlig;e Auswahl an warmen und kalten Speisen, Desserts, Obst und Gem&uuml;se.<\/li>\n\n\n\n<li><strong>Komfort und Aussicht:<\/strong> Die Kreuzfahrt findet auf einem Schiff mit klimatisierten oder beheizten Salons und einem Sonnendeck statt, von dem aus Sie die Karlsbr&uuml;cke, die Prager Burg, das Nationaltheater und andere architektonische Perlen bewundern k&ouml;nnen.<\/li>\n\n\n\n<li><strong>Die Atmosph&auml;re:<\/strong> An Bord gibt es Wi-Fi und eine Bar, an der Sie zus&auml;tzliche Getr&auml;nke kaufen k&ouml;nnen.<\/li>\n<\/ul>\n\n\n\n<p><strong>Diese Kreuzfahrt ist sehr beliebt und die Tickets sind schnell vergriffen! Sichern Sie sich fr&uuml;hzeitig Ihren Platz und buchen Sie Ihre Tickets im Voraus, damit Sie dieses unvergessliche Erlebnis nicht verpassen. <\/strong><\/p>\n\n\n\n<p>F&uuml;r weitere Informationen &uuml;ber die Kreuzfahrt und um zu buchen, klicken Sie auf den Link in der Schaltfl&auml;che:<\/p>\n\n\n<div class=\"tribe-block tribe-block__event-website\">\n\t<a href=\"https:\/\/praguecruises.eu\/de\/schifffahrt\/prager-nachtkreuzfahrt-mit-buffet-abendessen-und-aperitif\/\" target=\"_self\">\n\t\tPrager Nachtschifffahrt mit BUFFET-ABENDESSEN und Aperitif (20&ndash;22 Uhr)\t<\/a>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"tribe-events-single-section tribe-events-section-tags tribe-clearfix\">\n\t<li class=\"tribe-events-meta-item\"><span class=\"tribe-event-tags-label tribe-events-meta-label\">Schlagw&ouml;rter<\/span><span class=\"tribe-event-tags tribe-events-meta-value\"><a href=\"https:\/\/praguecruises.eu\/de\/Veranstaltungen\/Schlagwort\/kreuzfahrt\/\" rel=\"tag\">Kreuzfahrt<\/a>, <a href=\"https:\/\/praguecruises.eu\/de\/Veranstaltungen\/Schlagwort\/prag\/\" rel=\"tag\">Prag<\/a>, <a href=\"https:\/\/praguecruises.eu\/de\/Veranstaltungen\/Schlagwort\/raut-de\/\" rel=\"tag\">Raut<\/a><\/span><\/li><\/div>\n\n\n<div class=\"tribe-events-single-section tribe-events-section-category tribe-clearfix\">\n\t<dt class=\"tribe-events-event-categories-label\">Veranstaltungskategorie:<\/dt> <dd class=\"tribe-events-event-categories\"><a href=\"https:\/\/praguecruises.eu\/de\/events\/category\/fahren-sie-mit-dem-boot-auf-der-moldau-durch-prag\/\" rel=\"tag\">Fahren Sie mit dem Boot auf der Moldau durch Prag<\/a><\/dd><\/div>\n\n\n<div class=\"tribe-block tribe-block__organizer__details tribe-clearfix\">\n\t<div class=\"tribe-block__organizer__title\">\n\t\t<h3><a href=\"https:\/\/praguecruises.eu\/veranstalter\/prague-cruises\/\" title=\"PRAGUE CRUISES\" target=\"_self\" rel=\"\">PRAGUE CRUISES<\/a><\/h3>\n\t<\/div>\n\t\t\t\t<p class=\"tribe-block__organizer__website\"><a href=\"https:\/\/praguecruises.eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veranstalter-Website anzeigen<\/a><\/p>\n\t\t<\/div>\n\n\n<div class=\"tribe-block tribe-block__venue tribe-clearfix\">\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/praguecruises.eu\/veranstaltungsort\/plavba-po-rece-vltave-historickym-centrem-prahy\/\" title=\"Plavba po &#345;ece Vltav&#283; historick&yacute;m centrem Prahy\">Plavba po &#345;ece Vltav&#283; historick&yacute;m centrem Prahy<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">&#345;eka Vltava<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Praha<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\n\t<span class=\"tribe-country-name\">Czech Republic<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\n\t\t\t\n\t<\/div>\n\t\n\t<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Nachtfahrt durch Prag mit Buffet, September und Oktober 2025 &ndash; Erleben Sie einen einzigartigen Abend auf den Wellen der Moldau w&auml;hrend einer romantischen Nachtfahrt durch das historische Zentrum von Prag.<\/p>\n","protected":false},"author":1,"featured_media":20066,"template":"","meta":{"_tec_requires_first_save":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Prague","_EventStartDate":"2025-10-29 20:00:00","_EventEndDate":"2025-10-29 22:00:00","_EventStartDateUTC":"2025-10-29 19:00:00","_EventEndDateUTC":"2025-10-29 21:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"https:\/\/praguecruises.eu\/de\/schifffahrt\/prager-nachtkreuzfahrt-mit-buffet-abendessen-und-aperitif\/","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"CZK","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[10313],"_EventVenueID":[20028],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"daily\",\"limit_type\":\"date\",\"limit\":\"2025-10-31\",\"_limit_date_input\":\"October 31, 2025\",\"between\":1,\"start_time\":\"20:00:00\",\"end_time\":\"22:00:00\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[390,143,391],"tribe_events_cat":[449],"class_list":["post-10002824","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-kreuzfahrt","tag-prag","tag-raut-de","tribe_events_cat-fahren-sie-mit-dem-boot-auf-der-moldau-durch-prag","cat_fahren-sie-mit-dem-boot-auf-der-moldau-durch-prag","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events\/10002824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events\/10002824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/media\/20066"}],"wp:attachment":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/media?parent=10002824"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tags?post=10002824"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10002824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}