{"id":10001738,"date":"2025-07-12T14:09:33","date_gmt":"2025-07-12T12:09:33","guid":{"rendered":"https:\/\/praguecruises.eu\/event\/abendessen-auf-einem-schiff-nachtfahrt-durch-prag-juli-und-august-2025\/"},"modified":"2025-08-14T13:43:46","modified_gmt":"2025-08-14T11:43:46","slug":"abendessen-auf-einem-schiff-nachtfahrt-durch-prag-juli-und-august-2025","status":"publish","type":"tribe_events","link":"https:\/\/praguecruises.eu\/de\/event\/abendessen-auf-einem-schiff-nachtfahrt-durch-prag-juli-und-august-2025\/2025-07-01\/","title":{"rendered":"Abendessen auf dem Schiff &#8211; 3-st\u00fcndigen Nachtfahrt durch Prag, Juli und August 2025"},"content":{"rendered":"<div class=\"tribe-events-schedule tribe-clearfix\">\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\tJuli 1, 2025\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t, \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t19:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &ndash; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t22:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p><strong>Abendessen auf dem Schiff &ndash; eine dreist&uuml;ndige Nachtfahrt durch das historische Prag ist eine exklusive Nachtfahrt durch Prag.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Genie&szlig;en Sie einen Willkommensaperitif, ein reichhaltiges Buffet mit internationaler und tschechischer K&uuml;che, einen professionellen Audioguide und beleuchtete Szenen der Stadt in einer romantischen Atmosph&auml;re auf dem Wasser. Ideal f&uuml;r einen unterhaltsamen Abend mit Ihrem Partner, Freunden oder auch alleine. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#127769; Was steht f&uuml;r Sie an?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dauer der Kreuzfahrt:<\/strong> 3 Stunden auf der Moldau am Abend<\/li>\n\n\n\n<li><strong>Willkommens-Aperitif:<\/strong> Traditioneller tschechischer Lik&ouml;r als Willkommensgetr&auml;nk<\/li>\n\n\n\n<li><strong>Abendessen vom Buffet: eine<\/strong> Auswahl an warmen und kalten tschechischen und internationalen Gerichten<\/li>\n\n\n\n<li><strong>Audioguides in mehreren Sprachen:<\/strong> Kommentare zu den historischen Denkm&auml;lern entlang des Ufers<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">&#10024; Was werden Sie sehen?<\/h2>\n\n\n\n<p>Die Fahrt bietet einen atemberaubenden Blick auf die beleuchteten Sehensw&uuml;rdigkeiten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&lt;img width=&#039;200&#039; height=&#039;133&#039; src=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?fit=200%2C133&amp;amp;ssl=1&#039; class=&#039;cmtt-tooltip-featured-image wp-post-image&#039; alt=&#039;&#039; style=&#039;width: 200px; margin-top: 2%;float: right; margin-left: 2%;&#039; sizes=&#039;(max-width: 9999px) 200px,auto&#039; loading=&#039;eager&#039; srcset=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?w=1200&amp;amp;ssl=1 1200w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=324%2C216&amp;amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=416%2C277&amp;amp;ssl=1 416w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=300%2C200&amp;amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=1024%2C683&amp;amp;ssl=1 1024w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/karluv-most-vltava.jpg?resize=768%2C512&amp;amp;ssl=1 768w&#039; \/&gt;Die Karlsbr&uuml;cke ist eine historische Steinbr&uuml;cke in Prag &uuml;ber die Moldau. Die Br&uuml;cke wurde im Auftrag von Kaiser Karl IV. erbaut und ist eines der ber&uuml;hmtesten Denkm&auml;ler der Tschechischen Republik.&lt;\/div&gt;\"  href=\"https:\/\/praguecruises.eu\/de\/glossary\/karlsbruecke\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>Karlsbr&uuml;cke<\/a><\/li>\n\n\n\n<li><a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&lt;img width=&#039;200&#039; height=&#039;133&#039; src=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?fit=200%2C133&amp;amp;ssl=1&#039; class=&#039;cmtt-tooltip-featured-image wp-post-image&#039; alt=&#039;Prager burg&#039; style=&#039;width: 200px; margin-top: 2%;float: right; margin-left: 2%;&#039; sizes=&#039;(max-width: 9999px) 200px,auto&#039; loading=&#039;eager&#039; srcset=&#039;https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?w=1200&amp;amp;ssl=1 1200w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=324%2C216&amp;amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=416%2C277&amp;amp;ssl=1 416w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=300%2C200&amp;amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=1024%2C683&amp;amp;ssl=1 1024w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2024\/07\/hrad-prazsky-2.jpg?resize=768%2C512&amp;amp;ssl=1 768w&#039; \/&gt;Die Prager Burg ist eine historische Festung und der Sitz der tschechischen Herrscher und Pr&auml;sidenten in Prag. Sie ist einer der gr&ouml;&szlig;ten Burgkomplexe der Welt und eine wichtige Touristenattraktion. &lt;\/div&gt;\"  href=\"https:\/\/praguecruises.eu\/de\/glossary\/prager-burg\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>Prager Burg<\/a><\/li>\n\n\n\n<li>Rudolfinum, Nationaltheater, Vy&scaron;ehrad und andere&hellip;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">&#127881; F&uuml;r wen ist die Veranstaltung geeignet?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>F&uuml;r Paare<\/strong>, die einen romantischen Abend mit einem Glas Aperitif verbringen m&ouml;chten<\/li>\n\n\n\n<li><strong>F&uuml;r Einzelpersonen &ndash;<\/strong> es ist ein angenehmes gesellschaftliches Ereignis mit der M&ouml;glichkeit, andere zu treffen<\/li>\n\n\n\n<li><strong>F&uuml;r Touristen und Einheimische<\/strong>, die Prag aus einem anderen Blickwinkel, n&auml;mlich dem des Wassers, sehen m&ouml;chten<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/praguecruises.eu\/de\/?attachment_id=13107\" title=\"\">Abendessen an Bord mit Aperitif und Audioguide<\/a><\/h2>\n\n\n<figure style=\"aspect-ratio:16\/9; margin-top:0;margin-bottom:var(--wp--preset--spacing--40);\" class=\"wp-block-post-featured-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"653\" src=\"https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=980%2C653&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Ve&#269;e&#345;e na lodi - 3hodinov&aacute; no&#269;n&iacute; plavba historickou Prahou\" style=\"width:100%;height:100%;object-fit:cover;\" srcset=\"https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=324%2C216&amp;ssl=1 324w, https:\/\/i0.wp.com\/praguecruises.eu\/wp-content\/uploads\/2025\/07\/3hodinova-plavba-vecere.jpg?resize=416%2C277&amp;ssl=1 416w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\"\/><\/figure>\n\n\n<h3 class=\"wp-block-heading\">&#10133; Wie soll ich reagieren?<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Online-Reservierung<\/strong> &ndash; es ist notwendig, rechtzeitig vor der Veranstaltung online zu reservieren. Klicken Sie auf den Link in der Schaltfl&auml;che f&uuml;r weitere Informationen: <\/li>\n<\/ul>\n\n\n<div class=\"tribe-block tribe-block__event-website\">\n\t<a href=\"https:\/\/praguecruises.eu\/de\/schifffahrt\/3-stuendige-prager-nachtkreuzfahrt-mit-abendessen-aperitif-und-audioguide\/\" target=\"_self\">\n\t\t3-ST&Uuml;NDIGE Prager Nachtkreuzfahrt mit ABENDESSEN, Aperitif &amp; Audioguide\t<\/a>\n<\/div>\n\n\n<div class=\"tribe-block tribe-block__venue tribe-clearfix tribe-block__venue--has-map\">\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/praguecruises.eu\/veranstaltungsort\/praha\/\" title=\"Praha\">Praha<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">Praha<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Praha<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\n\t<span class=\"tribe-country-name\">Czech Republic<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-events-gmap\" href=\"https:\/\/maps.google.com\/maps?f=q&amp;source=s_q&amp;hl=en&amp;geocode=&amp;q=Praha+Praha+Czech+Republic\" title=\"Klicken, um Google Karte anzuzeigen\" target=\"_blank\" rel=\"noreferrer noopener\">Google Karte anzeigen<\/a>\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\n\t\t\t\n\t<\/div>\n\t\n<div class=\"tribe-block__venue__map\">\n\t\n<iframe loading=\"lazy\" title=\"Iframe von Google Maps, der die Adresse von Praha anzeigt\" aria-label=\"Karte des Veranstaltungsortes\" width=\"310px\" height=\"256px\" frameborder=\"0\" style=\"border:0\" src=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyDNsicAsP6-VuGtAb1O9riI3oc_NOb7IOU&amp;q=Praha+Praha+Czech+Republic+&amp;zoom=15\" allowfullscreen>\n<\/iframe>\n<\/div>\n\n\t<\/div>\n\n\n<div class=\"tribe-block tribe-block__organizer__details tribe-clearfix\">\n\t<div class=\"tribe-block__organizer__title\">\n\t\t<h3><a href=\"https:\/\/praguecruises.eu\/veranstalter\/prague-cruises\/\" title=\"PRAGUE CRUISES\" target=\"_self\" rel=\"\">PRAGUE CRUISES<\/a><\/h3>\n\t<\/div>\n\t\t\t\t<p class=\"tribe-block__organizer__website\"><a href=\"https:\/\/praguecruises.eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veranstalter-Website anzeigen<\/a><\/p>\n\t\t<\/div>\n\n\n\t<div class=\"tribe-block tribe-block__events-link\">\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" aria-hidden=\"true\" viewbox=\"0 0 23 17\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\"><\/path>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<\/svg>\n\t\t\t\t\t\t<button class=\"tribe-events-c-subscribe-dropdown__button-text\" aria-expanded=\"false\" aria-controls=\"tribe-events-subscribe-dropdown-content\" aria-label=\"Zeige Links an um Veranstaltungen zu deinem Kalender hinzuzuf&uuml;gen\">\n\t\t\t\t\t\t\tZum Kalender hinzuf&uuml;gen\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" aria-hidden=\"true\" viewbox=\"0 0 10 7\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;dates=20250701T190000\/20250701T220000&amp;text=Abendessen%20auf%20dem%20Schiff%20%26%238211%3B%203-st%C3%BCndigen%20Nachtfahrt%20durch%20Prag%2C%20Juli%20und%20August%202025&amp;details=%3Cp%3E%3Cstrong%3EAbendessen+auf+dem+Schiff+-+eine+dreist%C3%BCndige+Nachtfahrt+durch+das+historische+Prag+ist+eine+exklusive+Nachtfahrt+durch+Prag.%3C%2Fstrong%3E%3C%2Fp%3E+%3C%21--more--%3E%3Cp%3EGenie%C3%9Fen+Sie+einen+Willkommensaperitif%2C+ein+reichhaltiges+Buffet+mit+internationaler+und+tschechischer+K%C3%BCche%2C+einen+professionellen+Audioguide+und+beleuchtete+Szenen+der+Stadt+in+einer+romantischen+Atmosph%C3%A4re+auf+dem+Wasser.+Ideal+f%C3%BCr+einen+unterhaltsamen+Abend+mit+Ihrem+Partner%2C+Freunden+oder+auch+alleine.+%3C%2Fp%3E+%3Ch2+class%3D%22wp-block-heading%22%3E%F0%9F%8C%99+Was+steht+f%C3%BCr+Sie+an%3F%3C%2Fh2%3E%3Cul+class%3D%22wp-block-list%22%3E%3Cli%3E%3Cstrong%3EDauer+der+Kreuzfahrt%3A%3C%2Fstrong%3E+3+Stunden+auf+der+Moldau+am+Abend%3C%2Fli%3E%3Cli%3E%3Cstrong%3EWillkommens-Aperitif%3A%3C%2Fstrong%3E+Traditioneller+tschechischer+Lik%C3%B6r+als+Willkommensgetr%C3%A4nk%3C%2Fli%3E%3Cli%3E%3Cstrong%3EAbendessen+vom+Buffet%3A+eine%3C%2Fstrong%3E+Auswahl+an+warmen+und+kalten+tschechischen+und+internationalen+Gerichten%3C%2Fli%3E%3Cli%3E%3Cstrong%3EAudioguides+in+mehreren+Sprachen%3A%3C%2Fstrong%3E+Kommentare+zu+den+histori%3C%2Fli%3E%3C%2Ful%3E+%28Zeige+vollst%C3%A4ndige+Veranstaltung-Beschreibung+hier+an%3A+https%3A%2F%2Fpraguecruises.eu%2Fde%2Fevent%2Fabendessen-auf-einem-schiff-nachtfahrt-durch-prag-juli-und-august-2025%2F2025-07-01%2F%29&amp;location=Praha,%20Praha,%20Praha,%20Czech%20Republic&amp;trp=false&amp;ctz=Europe\/Prague&amp;sprop=website:https:\/\/praguecruises.eu\/de\/\" class=\"tribe-events-c-subscribe-dropdown__list-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow noindex\">\n\t\t\t\t\t\t\t\t\t\tGoogle Kalender\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"tribe-events-c-subscribe-dropdown__list-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow noindex\">\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"tribe-events-c-subscribe-dropdown__list-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow noindex\">\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"tribe-events-c-subscribe-dropdown__list-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow noindex\">\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Abendessen auf einem Schiff &ndash; eine dreist&uuml;ndige Nachtfahrt durch das historische Prag ist eine exklusive Nachtfahrt durch Prag.<\/p>\n","protected":false},"author":1,"featured_media":15742,"template":"","meta":{"_tec_requires_first_save":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Prague","_EventStartDate":"2025-07-01 19:00:00","_EventEndDate":"2025-07-01 22:00:00","_EventStartDateUTC":"2025-07-01 17:00:00","_EventEndDateUTC":"2025-07-01 20:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"https:\/\/praguecruises.eu\/de\/schifffahrt\/3-stuendige-prager-nachtkreuzfahrt-mit-abendessen-aperitif-und-audioguide\/","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"CZK","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[14862],"_EventVenueID":[7394],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"daily\",\"limit_type\":\"date\",\"limit\":\"2025-08-31\",\"_limit_date_input\":\"August 31, 2025\",\"between\":1,\"start_time\":\"19:00:00\",\"end_time\":\"22:00:00\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[581,390,391],"tribe_events_cat":[449],"class_list":["post-10001738","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-abendessen","tag-kreuzfahrt","tag-raut-de","tribe_events_cat-fahren-sie-mit-dem-boot-auf-der-moldau-durch-prag","cat_fahren-sie-mit-dem-boot-auf-der-moldau-durch-prag","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events\/10001738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events\/10001738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/media\/15742"}],"wp:attachment":[{"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/media?parent=10001738"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tags?post=10001738"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/praguecruises.eu\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10001738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}